{"id":60,"count":1,"description":"","link":"https:\/\/www.trekpedition.com\/stories\/category\/tanzania\/","name":"Tanzania","slug":"tanzania","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.trekpedition.com\/stories\/wp-json\/wp\/v2\/categories\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trekpedition.com\/stories\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.trekpedition.com\/stories\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.trekpedition.com\/stories\/wp-json\/wp\/v2\/posts?categories=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}